{"id":345,"date":"2022-11-24T10:57:55","date_gmt":"2022-11-24T01:57:55","guid":{"rendered":"https:\/\/blog.tokyoantioch.com\/2211sports\/?p=345"},"modified":"2022-11-24T10:58:16","modified_gmt":"2022-11-24T01:58:16","slug":"%e4%ba%a4%e9%80%9a%e4%ba%8b%e6%95%85%e3%80%82%e6%b2%bb%e3%81%a3%e3%81%9f%ef%bc%81","status":"publish","type":"post","link":"https:\/\/blog.tokyoantioch.com\/2211sports\/%e4%ba%a4%e9%80%9a%e4%ba%8b%e6%95%85%e3%80%82%e6%b2%bb%e3%81%a3%e3%81%9f%ef%bc%81\/","title":{"rendered":"\u4ea4\u901a\u4e8b\u6545\u3002\u6cbb\u3063\u305f\uff01"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-content\/uploads\/sites\/148\/2022\/11\/4A0BD28C-1523-44B5-80EA-FB0DD0DA2869.jpeg\" alt=\"\" class=\"wp-image-346\" srcset=\"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-content\/uploads\/sites\/148\/2022\/11\/4A0BD28C-1523-44B5-80EA-FB0DD0DA2869.jpeg 960w, https:\/\/blog.tokyoantioch.com\/2211sports\/wp-content\/uploads\/sites\/148\/2022\/11\/4A0BD28C-1523-44B5-80EA-FB0DD0DA2869-300x225.jpeg 300w, https:\/\/blog.tokyoantioch.com\/2211sports\/wp-content\/uploads\/sites\/148\/2022\/11\/4A0BD28C-1523-44B5-80EA-FB0DD0DA2869-768x576.jpeg 768w, https:\/\/blog.tokyoantioch.com\/2211sports\/wp-content\/uploads\/sites\/148\/2022\/11\/4A0BD28C-1523-44B5-80EA-FB0DD0DA2869-676x507.jpeg 676w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<p>\u4eca\u65e5\u306e\u5947\u8de1\u3002\u4ea4\u901a\u4e8b\u6545\u300246\u5e74\u7d9a\u3044\u305f\u8133\u632b\u50b7\u304c\u6cbb\u3063\u305f\u203c\ufe0f\u304a\u8a71\u3092\u805e\u3044\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u4eca\u65e5\u306e\u5947\u8de1\u3002\u4ea4\u901a\u4e8b\u6545\u300246\u5e74\u7d9a\u3044\u305f\u8133\u632b\u50b7\u304c\u6cbb\u3063\u305f\u203c\ufe0f\u304a\u8a71\u3092\u805e\u3044\u3066\u3044\u307e\u3059\u3002<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-345","post","type-post","status-publish","format-standard","hentry","category-uncategorized","post-preview"],"_links":{"self":[{"href":"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-json\/wp\/v2\/posts\/345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-json\/wp\/v2\/comments?post=345"}],"version-history":[{"count":2,"href":"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-json\/wp\/v2\/posts\/345\/revisions"}],"predecessor-version":[{"id":349,"href":"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-json\/wp\/v2\/posts\/345\/revisions\/349"}],"wp:attachment":[{"href":"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-json\/wp\/v2\/media?parent=345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-json\/wp\/v2\/categories?post=345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-json\/wp\/v2\/tags?post=345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}