{"id":66,"date":"2022-11-21T10:17:00","date_gmt":"2022-11-21T01:17:00","guid":{"rendered":"https:\/\/blog.tokyoantioch.com\/2211sports\/?p=66"},"modified":"2022-11-21T12:19:07","modified_gmt":"2022-11-21T03:19:07","slug":"%e6%9c%88%e6%9b%9c%e7%ac%ac%e4%b8%80%e7%a4%bc%e6%8b%9d-2","status":"publish","type":"post","link":"https:\/\/blog.tokyoantioch.com\/2211sports\/%e6%9c%88%e6%9b%9c%e7%ac%ac%e4%b8%80%e7%a4%bc%e6%8b%9d-2\/","title":{"rendered":"\u6708\u66dc\u7b2c\u4e00\u793c\u62dd"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-content\/uploads\/sites\/148\/2022\/11\/92C020A2-9FE4-422A-BABD-DE7B01BEDCF0.jpeg\" alt=\"\" class=\"wp-image-67\" srcset=\"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-content\/uploads\/sites\/148\/2022\/11\/92C020A2-9FE4-422A-BABD-DE7B01BEDCF0.jpeg 960w, https:\/\/blog.tokyoantioch.com\/2211sports\/wp-content\/uploads\/sites\/148\/2022\/11\/92C020A2-9FE4-422A-BABD-DE7B01BEDCF0-300x225.jpeg 300w, https:\/\/blog.tokyoantioch.com\/2211sports\/wp-content\/uploads\/sites\/148\/2022\/11\/92C020A2-9FE4-422A-BABD-DE7B01BEDCF0-768x576.jpeg 768w, https:\/\/blog.tokyoantioch.com\/2211sports\/wp-content\/uploads\/sites\/148\/2022\/11\/92C020A2-9FE4-422A-BABD-DE7B01BEDCF0-676x507.jpeg 676w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-content\/uploads\/sites\/148\/2022\/11\/C72DDC21-E5AB-456F-AE39-BE3EAF8D72E3.jpeg\" alt=\"\" class=\"wp-image-68\" srcset=\"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-content\/uploads\/sites\/148\/2022\/11\/C72DDC21-E5AB-456F-AE39-BE3EAF8D72E3.jpeg 960w, https:\/\/blog.tokyoantioch.com\/2211sports\/wp-content\/uploads\/sites\/148\/2022\/11\/C72DDC21-E5AB-456F-AE39-BE3EAF8D72E3-300x225.jpeg 300w, https:\/\/blog.tokyoantioch.com\/2211sports\/wp-content\/uploads\/sites\/148\/2022\/11\/C72DDC21-E5AB-456F-AE39-BE3EAF8D72E3-768x576.jpeg 768w, https:\/\/blog.tokyoantioch.com\/2211sports\/wp-content\/uploads\/sites\/148\/2022\/11\/C72DDC21-E5AB-456F-AE39-BE3EAF8D72E3-676x507.jpeg 676w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<p>\u59cb\u307e\u308a\u307e\u3057\u305f\uff01<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u59cb\u307e\u308a\u307e\u3057\u305f\uff01<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-66","post","type-post","status-publish","format-standard","hentry","category-uncategorized","post-preview"],"_links":{"self":[{"href":"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-json\/wp\/v2\/posts\/66","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-json\/wp\/v2\/comments?post=66"}],"version-history":[{"count":1,"href":"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-json\/wp\/v2\/posts\/66\/revisions"}],"predecessor-version":[{"id":69,"href":"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-json\/wp\/v2\/posts\/66\/revisions\/69"}],"wp:attachment":[{"href":"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-json\/wp\/v2\/media?parent=66"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-json\/wp\/v2\/categories?post=66"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2211sports\/wp-json\/wp\/v2\/tags?post=66"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}