{"id":476,"date":"2023-01-22T07:24:29","date_gmt":"2023-01-21T22:24:29","guid":{"rendered":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/?p=476"},"modified":"2023-01-22T07:24:29","modified_gmt":"2023-01-21T22:24:29","slug":"%e5%be%8c%e5%8d%8a%e8%b3%9b%e7%be%8e-5","status":"publish","type":"post","link":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/%e5%be%8c%e5%8d%8a%e8%b3%9b%e7%be%8e-5\/","title":{"rendered":"\u5f8c\u534a\u8cdb\u7f8e"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-content\/uploads\/sites\/159\/2023\/01\/img_5374.jpg\" class=\"wp-image-475\" \/><\/figure>\n\n\n\n<p>\u8cdb\u7f8e\u306e\u3068\u304d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u8cdb\u7f8e\u306e\u3068\u304d<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-476","post","type-post","status-publish","format-standard","hentry","category-uncategorized","post-preview"],"_links":{"self":[{"href":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-json\/wp\/v2\/posts\/476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-json\/wp\/v2\/comments?post=476"}],"version-history":[{"count":1,"href":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-json\/wp\/v2\/posts\/476\/revisions"}],"predecessor-version":[{"id":477,"href":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-json\/wp\/v2\/posts\/476\/revisions\/477"}],"wp:attachment":[{"href":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-json\/wp\/v2\/media?parent=476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-json\/wp\/v2\/categories?post=476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-json\/wp\/v2\/tags?post=476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}