{"id":61,"date":"2023-01-16T13:03:57","date_gmt":"2023-01-16T04:03:57","guid":{"rendered":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/?p=61"},"modified":"2023-01-16T13:03:58","modified_gmt":"2023-01-16T04:03:58","slug":"%e6%9c%88%e6%9b%9c%e7%ac%ac%e4%ba%8c%e7%a4%bc%e6%8b%9d","status":"publish","type":"post","link":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/%e6%9c%88%e6%9b%9c%e7%ac%ac%e4%ba%8c%e7%a4%bc%e6%8b%9d\/","title":{"rendered":"\u6708\u66dc\u7b2c\u4e8c\u793c\u62dd"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"224\" src=\"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-content\/uploads\/sites\/159\/2023\/01\/img_4780.jpg\" class=\"wp-image-60\" \/><\/figure>\n\n\n\n<p>\u6708\u66dc\u7b2c\u4e8c\u793c\u62dd\u304c\u30b9\u30bf\u30fc\u30c8\u3057\u307e\u3057\u305f\uff01<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u6708\u66dc\u7b2c\u4e8c\u793c\u62dd\u304c\u30b9\u30bf\u30fc\u30c8\u3057\u307e\u3057\u305f\uff01<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-61","post","type-post","status-publish","format-standard","hentry","category-uncategorized","post-preview"],"_links":{"self":[{"href":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-json\/wp\/v2\/posts\/61","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-json\/wp\/v2\/comments?post=61"}],"version-history":[{"count":1,"href":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-json\/wp\/v2\/posts\/61\/revisions"}],"predecessor-version":[{"id":62,"href":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-json\/wp\/v2\/posts\/61\/revisions\/62"}],"wp:attachment":[{"href":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-json\/wp\/v2\/media?parent=61"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-json\/wp\/v2\/categories?post=61"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2301dontlose\/wp-json\/wp\/v2\/tags?post=61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}