{"id":556,"date":"2023-06-03T11:59:31","date_gmt":"2023-06-03T02:59:31","guid":{"rendered":"https:\/\/blog.tokyoantioch.com\/2305syoka\/?p=556"},"modified":"2023-06-03T11:59:31","modified_gmt":"2023-06-03T02:59:31","slug":"%e5%8f%b0%e9%a2%a8","status":"publish","type":"post","link":"https:\/\/blog.tokyoantioch.com\/2305syoka\/%e5%8f%b0%e9%a2%a8\/","title":{"rendered":"\u53f0\u98a8"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/blog.tokyoantioch.com\/2305syoka\/wp-content\/uploads\/sites\/181\/2023\/06\/55825E47-3F7D-4086-BC86-FC971C6C4F01.jpeg\" alt=\"\" class=\"wp-image-557\" srcset=\"https:\/\/blog.tokyoantioch.com\/2305syoka\/wp-content\/uploads\/sites\/181\/2023\/06\/55825E47-3F7D-4086-BC86-FC971C6C4F01.jpeg 640w, https:\/\/blog.tokyoantioch.com\/2305syoka\/wp-content\/uploads\/sites\/181\/2023\/06\/55825E47-3F7D-4086-BC86-FC971C6C4F01-300x225.jpeg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p>\u96e8\u306f\u4e0a\u304c\u308a\u307e\u3057\u305f\uff01<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u96e8\u306f\u4e0a\u304c\u308a\u307e\u3057\u305f\uff01<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-556","post","type-post","status-publish","format-standard","hentry","category-uncategorized","post-preview"],"_links":{"self":[{"href":"https:\/\/blog.tokyoantioch.com\/2305syoka\/wp-json\/wp\/v2\/posts\/556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.tokyoantioch.com\/2305syoka\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.tokyoantioch.com\/2305syoka\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2305syoka\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2305syoka\/wp-json\/wp\/v2\/comments?post=556"}],"version-history":[{"count":1,"href":"https:\/\/blog.tokyoantioch.com\/2305syoka\/wp-json\/wp\/v2\/posts\/556\/revisions"}],"predecessor-version":[{"id":558,"href":"https:\/\/blog.tokyoantioch.com\/2305syoka\/wp-json\/wp\/v2\/posts\/556\/revisions\/558"}],"wp:attachment":[{"href":"https:\/\/blog.tokyoantioch.com\/2305syoka\/wp-json\/wp\/v2\/media?parent=556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2305syoka\/wp-json\/wp\/v2\/categories?post=556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2305syoka\/wp-json\/wp\/v2\/tags?post=556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}