{"id":212,"date":"2024-10-02T14:15:26","date_gmt":"2024-10-02T05:15:26","guid":{"rendered":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/?p=212"},"modified":"2024-10-02T14:15:26","modified_gmt":"2024-10-02T05:15:26","slug":"%e5%bd%a9%e9%9b%b2-2","status":"publish","type":"post","link":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/%e5%bd%a9%e9%9b%b2-2\/","title":{"rendered":"\u5f69\u96f2"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"168\" src=\"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-content\/uploads\/sites\/252\/2024\/10\/img_8755-1.jpg\" class=\"wp-image-211\" \/><\/figure>\n\n\n\n<p>\u30ad\u30ec\u30a4\u306a\u5f69\u96f2\u51fa\u3066\u3044\u307e\u3057\u305f\uff01\u30aa\u30f3\u30e9\u30a4\u30f3\u4f1a\u54e1M<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u30ad\u30ec\u30a4\u306a\u5f69\u96f2\u51fa\u3066\u3044\u307e\u3057\u305f\uff01\u30aa\u30f3\u30e9\u30a4\u30f3\u4f1a\u54e1M<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-212","post","type-post","status-publish","format-standard","hentry","category-uncategorized","post-preview"],"_links":{"self":[{"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/posts\/212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/comments?post=212"}],"version-history":[{"count":1,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/posts\/212\/revisions"}],"predecessor-version":[{"id":213,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/posts\/212\/revisions\/213"}],"wp:attachment":[{"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/media?parent=212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/categories?post=212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/tags?post=212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}