{"id":236,"date":"2024-10-02T19:18:30","date_gmt":"2024-10-02T10:18:30","guid":{"rendered":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/?p=236"},"modified":"2024-10-02T19:18:30","modified_gmt":"2024-10-02T10:18:30","slug":"%e5%89%b5%e4%b8%96%e8%a8%98","status":"publish","type":"post","link":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/%e5%89%b5%e4%b8%96%e8%a8%98\/","title":{"rendered":"\u5275\u4e16\u8a18"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-content\/uploads\/sites\/252\/2024\/10\/img_9095-1.jpg\" class=\"wp-image-235\" \/><\/figure>\n\n\n\n<p>25\u7ae0\u304b\u3089\u8a9e\u3089\u308c\u307e\u3059<\/p>\n","protected":false},"excerpt":{"rendered":"<p>25\u7ae0\u304b\u3089\u8a9e\u3089\u308c\u307e\u3059<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-236","post","type-post","status-publish","format-standard","hentry","category-uncategorized","post-preview"],"_links":{"self":[{"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/posts\/236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/comments?post=236"}],"version-history":[{"count":1,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/posts\/236\/revisions"}],"predecessor-version":[{"id":237,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/posts\/236\/revisions\/237"}],"wp:attachment":[{"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/media?parent=236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/categories?post=236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/tags?post=236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}