{"id":271,"date":"2024-10-03T10:39:54","date_gmt":"2024-10-03T01:39:54","guid":{"rendered":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/?p=271"},"modified":"2024-10-03T10:39:54","modified_gmt":"2024-10-03T01:39:54","slug":"%e5%a5%8f%e6%a5%bd","status":"publish","type":"post","link":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/%e5%a5%8f%e6%a5%bd\/","title":{"rendered":"\u594f\u697d"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"224\" src=\"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-content\/uploads\/sites\/252\/2024\/10\/img_1164-1-300x224.jpg\" class=\"wp-image-270\" srcset=\"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-content\/uploads\/sites\/252\/2024\/10\/img_1164-1-300x224.jpg 300w, https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-content\/uploads\/sites\/252\/2024\/10\/img_1164-1-768x574.jpg 768w, https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-content\/uploads\/sites\/252\/2024\/10\/img_1164-1-676x505.jpg 676w, https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-content\/uploads\/sites\/252\/2024\/10\/img_1164-1.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<p>\u594f\u697d\u8005\u306e\u6df1\u6fa4\u3055\u3093\u3067\u3059\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u594f\u697d\u8005\u306e\u6df1\u6fa4\u3055\u3093\u3067\u3059\u3002<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-271","post","type-post","status-publish","format-standard","hentry","category-uncategorized","post-preview"],"_links":{"self":[{"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/posts\/271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/comments?post=271"}],"version-history":[{"count":1,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/posts\/271\/revisions"}],"predecessor-version":[{"id":272,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/posts\/271\/revisions\/272"}],"wp:attachment":[{"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/media?parent=271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/categories?post=271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/tags?post=271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}