{"id":532,"date":"2024-10-06T09:15:56","date_gmt":"2024-10-06T00:15:56","guid":{"rendered":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/?p=532"},"modified":"2024-10-06T09:15:56","modified_gmt":"2024-10-06T00:15:56","slug":"%e3%83%86%e3%83%a2%e3%83%86%e5%b0%8f%e6%9e%97%e3%81%95%e3%82%93%e3%81%8c","status":"publish","type":"post","link":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/%e3%83%86%e3%83%a2%e3%83%86%e5%b0%8f%e6%9e%97%e3%81%95%e3%82%93%e3%81%8c\/","title":{"rendered":"\u30c6\u30e2\u30c6\u5c0f\u6797\u3055\u3093\u304c"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-content\/uploads\/sites\/252\/2024\/10\/img_9124-1.jpg\" class=\"wp-image-531\" \/><\/figure>\n\n\n\n<p>\u30a8\u30eb\u30b5\u30ec\u30e0\u306e\u5e73\u548c\u306e\u305f\u3081\u306b\u304a\u7948\u308a\u3057\u307e\u3059<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u30a8\u30eb\u30b5\u30ec\u30e0\u306e\u5e73\u548c\u306e\u305f\u3081\u306b\u304a\u7948\u308a\u3057\u307e\u3059<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-532","post","type-post","status-publish","format-standard","hentry","category-uncategorized","post-preview"],"_links":{"self":[{"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/posts\/532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/comments?post=532"}],"version-history":[{"count":1,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/posts\/532\/revisions"}],"predecessor-version":[{"id":533,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/posts\/532\/revisions\/533"}],"wp:attachment":[{"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/media?parent=532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/categories?post=532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/tags?post=532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}