{"id":58,"date":"2024-09-30T11:24:31","date_gmt":"2024-09-30T02:24:31","guid":{"rendered":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/?p=58"},"modified":"2024-09-30T11:24:31","modified_gmt":"2024-09-30T02:24:31","slug":"%e3%83%8f%e3%83%ac%e3%83%ab%e3%83%a4","status":"publish","type":"post","link":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/%e3%83%8f%e3%83%ac%e3%83%ab%e3%83%a4\/","title":{"rendered":"\u30cf\u30ec\u30eb\u30e4"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-content\/uploads\/sites\/252\/2024\/09\/img_9082-1.jpg\" class=\"wp-image-57\" \/><figcaption class=\"wp-element-caption\">\u795d\u7977\u3067\u3059<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-58","post","type-post","status-publish","format-standard","hentry","category-uncategorized","post-preview"],"_links":{"self":[{"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/posts\/58","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/comments?post=58"}],"version-history":[{"count":1,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/posts\/58\/revisions"}],"predecessor-version":[{"id":59,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/posts\/58\/revisions\/59"}],"wp:attachment":[{"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/media?parent=58"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/categories?post=58"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.tokyoantioch.com\/2410jerusalem\/wp-json\/wp\/v2\/tags?post=58"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}